{"id":23118,"date":"2026-07-14T23:50:47","date_gmt":"2026-07-14T23:50:47","guid":{"rendered":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/"},"modified":"2026-07-14T23:50:47","modified_gmt":"2026-07-14T23:50:47","slug":"apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso","status":"publish","type":"post","link":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/","title":{"rendered":"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso?"},"content":{"rendered":"<p><\/p>\n<div>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-91165\" src=\"https:\/\/windowsclub.com.br\/wp-content\/uploads\/2023\/06\/starfield-lua-saturno.jpg\" alt=\"\" width=\"1138\" height=\"658\" srcset=\"https:\/\/windowsclub.com.br\/wp-content\/uploads\/2023\/06\/starfield-lua-saturno.jpg 1138w, https:\/\/windowsclub.com.br\/wp-content\/uploads\/2023\/06\/starfield-lua-saturno-300x173.jpg 300w, https:\/\/windowsclub.com.br\/wp-content\/uploads\/2023\/06\/starfield-lua-saturno-1024x592.jpg 1024w, https:\/\/windowsclub.com.br\/wp-content\/uploads\/2023\/06\/starfield-lua-saturno-768x444.jpg 768w, https:\/\/windowsclub.com.br\/wp-content\/uploads\/2023\/06\/starfield-lua-saturno-200x116.jpg 200w, https:\/\/windowsclub.com.br\/wp-content\/uploads\/2023\/06\/starfield-lua-saturno-690x399.jpg 690w\" sizes=\"(max-width: 1138px) 100vw, 1138px\"\/><\/p>\n<p style=\"text-align: justify;\">O Xbox Game Pass se tornou alvo de uma nova pol\u00eamica nas redes sociais. Um tweet que viralizou afirmou que a Microsoft considera que lan\u00e7ar jogos \u201cday one\u201d no lan\u00e7amento seria uma estrat\u00e9gia fracassada. Isso gerou forte repercuss\u00e3o, compartilhamentos em massa, mas realmente esta frase foi afirmada pela Microsoft?<\/p>\n<p style=\"text-align: justify;\">O espanhol eXtas1stv postou o seguinte texto:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><strong>BLOOMBERG<\/strong>: A Microsoft admitiu internamente que lan\u00e7ar seus jogos no Dia 1 no Game Pass tem sido uma \u201caposta fracassada\u201d que est\u00e1 destruindo seus pr\u00f3prios lucros.<\/p>\n<p style=\"text-align: justify;\">O vazamento revelada pela Bloomberg exp\u00f5e um buraco financeiro:<\/p>\n<p style=\"text-align: justify;\"><strong>Canibaliza\u00e7\u00e3o massiva<\/strong>: A diretoria assume que os jogadores preferem pagar a assinatura em vez do jogo a 70 d\u00f3lares, afundando as vendas diretas dos t\u00edtulos AAA do Xbox em at\u00e9 80%.<\/p>\n<p style=\"text-align: justify;\"><strong>O desastre de Call of Duty<\/strong>: Os analistas internos estimam que incluir a franquia estrela no servi\u00e7o custou \u00e0 companhia cerca de 300 milh\u00f5es de d\u00f3lares em perdas de receita.<\/p>\n<p style=\"text-align: justify;\"><strong>Guerra interna<\/strong>: M\u00faltiplos executivos se opuseram frontalmente a essa estrat\u00e9gia, argumentando que o modelo atual desvaloriza suas superprodu\u00e7\u00f5es e s\u00f3 \u00e9 rent\u00e1vel para o usu\u00e1rio, n\u00e3o para a empresa.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">O Xbox Game Pass foi lan\u00e7ado em primeiro de junho de 2017, h\u00e1 um pouco mais de nove anos. Ent\u00e3o quer dizer que em quase uma d\u00e9cada de servi\u00e7o oferecendo benef\u00edcios para os seus jogadores, a Microsoft agora entende que o Game Pass \u00e9 uma \u201caposta fracassada\u201d.<\/p>\n<p style=\"text-align: justify;\">Na verdade a comunidade gamer contestou a informa\u00e7\u00e3o de eXtas1stv e <strong>tomou a seguinte nota<\/strong>:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">A Bloomberg n\u00e3o relatou que a Microsoft concluiu que o Game Pass no Dia 1 \u00e9 uma \u201caposta fracassada\u201d. Esta postagem \u00e9 baseada em um relat\u00f3rio da Bloomberg de uma semana que discutiu compensa\u00e7\u00f5es espec\u00edficas de receita relacionadas a Call of Duty, n\u00e3o \u00e0 estrat\u00e9gia completa do Game Pass no Dia 1 do Xbox.<\/p>\n<\/blockquote>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"es\" dir=\"ltr\">BLOOMBERG \u203c\ufe0f : Microsoft ha admitido internamente que lanzar sus juegos D\u00eda 1 en Game Pass ha sido una &#8220;apuesta fallida&#8221; que est\u00e1 destruyendo sus propios ingresos.<\/p>\n<p>\u200bLa filtraci\u00f3n revelada por Bloomberg expone un agujero financiero:<\/p>\n<p>\u27a1\ufe0f \u200bCanibalizaci\u00f3n masiva: La directiva asume\u2026 <a href=\"https:\/\/t.co\/f22hdr1cmq\">pic.twitter.com\/f22hdr1cmq<\/a><\/p>\n<p>\u2014 eXtas1s \ud83c\udfae Noticias &amp; Rumores (@eXtas1stv) <a href=\"https:\/\/x.com\/eXtas1stv\/status\/2077036155187446100?ref_src=twsrc%5Etfw\">July 14, 2026<\/a><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Na verdade, a Bloomberg fez uma mat\u00e9ria falando especificamente de Call of Duty, e mesmo assim acabou sendo contestada pois esqueceu de analisar diversos fatos como microtransa\u00e7\u00f5es ou pessoas que n\u00e3o comprariam Call of Duty: Black Ops 6, mas s\u00f3 jogaram por estarem no Xbox Game Pass.<\/p>\n<p style=\"text-align: justify;\">Mat Piscatella rebateu ao <a href=\"http:\/\/x.com\/IdleSloth84_\/status\/2074614439962456068\" target=\"_blank\" rel=\"noopener\">afirmar<\/a>:<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">De qualquer forma, a obje\u00e7\u00e3o que tenho \u00e9 com o n\u00famero de US$ 300 milh\u00f5es em vendas perdidas de COD. Pelo que posso constatar, isso \u00e9 matem\u00e1tica de pirataria. (Que qualquer um que jogou via Game Pass foi uma venda perdida \u2013 o que n\u00e3o \u00e9 verdade \u2013 assim como toda c\u00f3pia pirateada n\u00e3o \u00e9 uma venda perdida) e n\u00e3o leva em conta as receitas de assinaturas. Mas tanto faz, obje\u00e7\u00e3o menor.<\/p>\n<p style=\"text-align: justify;\">\u2026.<\/p>\n<p style=\"text-align: justify;\">Ah sim, 2\u00ba de qualquer forma\u2026 Mesmo se o Game Pass for encerrado amanh\u00e3, isso n\u00e3o significa que veremos um aumento nas vendas dos jogos envolvidos. Um impulso? Claro. Mas o impacto negativo do Game Pass nas vendas de jogos \u00e9 ALTAMENTE superestimado, com base nos dados que vi. Mas tanto faz.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Dessa forma, sempre devemos ter cuidado com as informa\u00e7\u00f5es que recebemos na internet\u2026<\/p>\n<p><!-- CONTENT END 2 -->\n\t<\/div>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Xbox Game Pass se tornou alvo de uma nova pol\u00eamica nas redes sociais. Um tweet que viralizou afirmou que a Microsoft considera que lan\u00e7ar jogos \u201cday one\u201d no lan\u00e7amento seria uma estrat\u00e9gia fracassada. Isso gerou forte repercuss\u00e3o, compartilhamentos em massa, mas realmente esta frase foi afirmada pela Microsoft? O espanhol eXtas1stv postou o seguinte &hellip;<\/p>\n","protected":false},"author":1,"featured_media":13017,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[86],"tags":[],"coauthors":[393],"class_list":["post-23118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-xbox"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"O Xbox Game Pass se tornou alvo de uma nova pol\u00eamica nas redes sociais. Um tweet que viralizou afirmou que a Microsoft considera que lan\u00e7ar jogos \u201cday one\u201d no lan\u00e7amento seria uma estrat\u00e9gia fracassada. Isso gerou forte repercuss\u00e3o, compartilhamentos em massa, mas realmente esta frase foi afirmada pela Microsoft? O espanhol eXtas1stv postou o seguinte\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Fagner Lopes\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Obewise - Entretenimento e Network\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso? - Obewise\" \/>\n\t\t<meta property=\"og:description\" content=\"O Xbox Game Pass se tornou alvo de uma nova pol\u00eamica nas redes sociais. Um tweet que viralizou afirmou que a Microsoft considera que lan\u00e7ar jogos \u201cday one\u201d no lan\u00e7amento seria uma estrat\u00e9gia fracassada. Isso gerou forte repercuss\u00e3o, compartilhamentos em massa, mas realmente esta frase foi afirmada pela Microsoft? O espanhol eXtas1stv postou o seguinte\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-07-14T23:50:47+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-07-14T23:50:47+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/obewisenetwork\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@obewisenetwork\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso? - Obewise\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O Xbox Game Pass se tornou alvo de uma nova pol\u00eamica nas redes sociais. Um tweet que viralizou afirmou que a Microsoft considera que lan\u00e7ar jogos \u201cday one\u201d no lan\u00e7amento seria uma estrat\u00e9gia fracassada. Isso gerou forte repercuss\u00e3o, compartilhamentos em massa, mas realmente esta frase foi afirmada pela Microsoft? O espanhol eXtas1stv postou o seguinte\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@obewisenetwork\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#blogposting\",\"name\":\"Ap\\u00f3s 9 anos, Microsoft acredita que lan\\u00e7ar jogos direto no Xbox Game Pass \\u00e9 um fracasso? - Obewise\",\"headline\":\"Ap\\u00f3s 9 anos, Microsoft acredita que lan\\u00e7ar jogos direto no Xbox Game Pass \\u00e9 um fracasso?\",\"author\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/author\\\/fagnerlopes\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/starfield-lua-saturno.jpg\",\"width\":1138,\"height\":658},\"datePublished\":\"2026-07-14T23:50:47+00:00\",\"dateModified\":\"2026-07-14T23:50:47+00:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#webpage\"},\"articleSection\":\"Xbox, FagnerLopes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/obewise.com.br\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/games\\\/#listItem\",\"name\":\"Games\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/games\\\/#listItem\",\"position\":2,\"name\":\"Games\",\"item\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/games\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/games\\\/xbox\\\/#listItem\",\"name\":\"Xbox\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/games\\\/xbox\\\/#listItem\",\"position\":3,\"name\":\"Xbox\",\"item\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/games\\\/xbox\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#listItem\",\"name\":\"Ap\\u00f3s 9 anos, Microsoft acredita que lan\\u00e7ar jogos direto no Xbox Game Pass \\u00e9 um fracasso?\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/games\\\/#listItem\",\"name\":\"Games\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#listItem\",\"position\":4,\"name\":\"Ap\\u00f3s 9 anos, Microsoft acredita que lan\\u00e7ar jogos direto no Xbox Game Pass \\u00e9 um fracasso?\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/games\\\/xbox\\\/#listItem\",\"name\":\"Xbox\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/#organization\",\"name\":\"Obewise Entertainment Network\",\"description\":\"Entretenimento e Network\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/\",\"telephone\":\"+5511963153854\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/abstract-logo-maker-for-corporations-1530.png\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#organizationLogo\",\"width\":4000,\"height\":4000},\"image\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/obewisenetwork\",\"https:\\\/\\\/twitter.com\\\/obewisenetwork\",\"https:\\\/\\\/www.instagram.com\\\/obewise.network\\\/\",\"https:\\\/\\\/soundcloud.com\\\/obewiseradio\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/author\\\/fagnerlopes\\\/#author\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/author\\\/fagnerlopes\\\/\",\"name\":\"Fagner Lopes\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#authorImage\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/wp-content\\\/uploads\\\/avatars\\\/1\\\/1668544069-bpfull.jpg\",\"width\":96,\"height\":96,\"caption\":\"Fagner Lopes\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#webpage\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/\",\"name\":\"Ap\\u00f3s 9 anos, Microsoft acredita que lan\\u00e7ar jogos direto no Xbox Game Pass \\u00e9 um fracasso? - Obewise\",\"description\":\"O Xbox Game Pass se tornou alvo de uma nova pol\\u00eamica nas redes sociais. Um tweet que viralizou afirmou que a Microsoft considera que lan\\u00e7ar jogos \\u201cday one\\u201d no lan\\u00e7amento seria uma estrat\\u00e9gia fracassada. Isso gerou forte repercuss\\u00e3o, compartilhamentos em massa, mas realmente esta frase foi afirmada pela Microsoft? O espanhol eXtas1stv postou o seguinte\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/author\\\/fagnerlopes\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/author\\\/fagnerlopes\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/starfield-lua-saturno.jpg\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#mainImage\",\"width\":1138,\"height\":658},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/07\\\/14\\\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\\\/#mainImage\"},\"datePublished\":\"2026-07-14T23:50:47+00:00\",\"dateModified\":\"2026-07-14T23:50:47+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/#website\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/\",\"name\":\"Obewise\",\"description\":\"Entretenimento e Network\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso? - Obewise","description":"O Xbox Game Pass se tornou alvo de uma nova pol\u00eamica nas redes sociais. Um tweet que viralizou afirmou que a Microsoft considera que lan\u00e7ar jogos \u201cday one\u201d no lan\u00e7amento seria uma estrat\u00e9gia fracassada. Isso gerou forte repercuss\u00e3o, compartilhamentos em massa, mas realmente esta frase foi afirmada pela Microsoft? O espanhol eXtas1stv postou o seguinte","canonical_url":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#blogposting","name":"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso? - Obewise","headline":"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso?","author":{"@id":"https:\/\/obewise.com.br\/index.php\/author\/fagnerlopes\/#author"},"publisher":{"@id":"https:\/\/obewise.com.br\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/obewise.com.br\/wp-content\/uploads\/2024\/10\/starfield-lua-saturno.jpg","width":1138,"height":658},"datePublished":"2026-07-14T23:50:47+00:00","dateModified":"2026-07-14T23:50:47+00:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#webpage"},"isPartOf":{"@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#webpage"},"articleSection":"Xbox, FagnerLopes"},{"@type":"BreadcrumbList","@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/obewise.com.br#listItem","position":1,"name":"Home","item":"https:\/\/obewise.com.br","nextItem":{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/category\/games\/#listItem","name":"Games"}},{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/category\/games\/#listItem","position":2,"name":"Games","item":"https:\/\/obewise.com.br\/index.php\/category\/games\/","nextItem":{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/category\/games\/xbox\/#listItem","name":"Xbox"},"previousItem":{"@type":"ListItem","@id":"https:\/\/obewise.com.br#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/category\/games\/xbox\/#listItem","position":3,"name":"Xbox","item":"https:\/\/obewise.com.br\/index.php\/category\/games\/xbox\/","nextItem":{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#listItem","name":"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso?"},"previousItem":{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/category\/games\/#listItem","name":"Games"}},{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#listItem","position":4,"name":"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso?","previousItem":{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/category\/games\/xbox\/#listItem","name":"Xbox"}}]},{"@type":"Organization","@id":"https:\/\/obewise.com.br\/#organization","name":"Obewise Entertainment Network","description":"Entretenimento e Network","url":"https:\/\/obewise.com.br\/","telephone":"+5511963153854","logo":{"@type":"ImageObject","url":"https:\/\/obewise.com.br\/wp-content\/uploads\/2022\/12\/abstract-logo-maker-for-corporations-1530.png","@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#organizationLogo","width":4000,"height":4000},"image":{"@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/obewisenetwork","https:\/\/twitter.com\/obewisenetwork","https:\/\/www.instagram.com\/obewise.network\/","https:\/\/soundcloud.com\/obewiseradio"]},{"@type":"Person","@id":"https:\/\/obewise.com.br\/index.php\/author\/fagnerlopes\/#author","url":"https:\/\/obewise.com.br\/index.php\/author\/fagnerlopes\/","name":"Fagner Lopes","image":{"@type":"ImageObject","@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#authorImage","url":"https:\/\/obewise.com.br\/wp-content\/uploads\/avatars\/1\/1668544069-bpfull.jpg","width":96,"height":96,"caption":"Fagner Lopes"}},{"@type":"WebPage","@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#webpage","url":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/","name":"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso? - Obewise","description":"O Xbox Game Pass se tornou alvo de uma nova pol\u00eamica nas redes sociais. Um tweet que viralizou afirmou que a Microsoft considera que lan\u00e7ar jogos \u201cday one\u201d no lan\u00e7amento seria uma estrat\u00e9gia fracassada. Isso gerou forte repercuss\u00e3o, compartilhamentos em massa, mas realmente esta frase foi afirmada pela Microsoft? O espanhol eXtas1stv postou o seguinte","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/obewise.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#breadcrumblist"},"author":{"@id":"https:\/\/obewise.com.br\/index.php\/author\/fagnerlopes\/#author"},"creator":{"@id":"https:\/\/obewise.com.br\/index.php\/author\/fagnerlopes\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/obewise.com.br\/wp-content\/uploads\/2024\/10\/starfield-lua-saturno.jpg","@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#mainImage","width":1138,"height":658},"primaryImageOfPage":{"@id":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/#mainImage"},"datePublished":"2026-07-14T23:50:47+00:00","dateModified":"2026-07-14T23:50:47+00:00"},{"@type":"WebSite","@id":"https:\/\/obewise.com.br\/#website","url":"https:\/\/obewise.com.br\/","name":"Obewise","description":"Entretenimento e Network","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/obewise.com.br\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Obewise - Entretenimento e Network","og:type":"article","og:title":"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso? - Obewise","og:description":"O Xbox Game Pass se tornou alvo de uma nova pol\u00eamica nas redes sociais. Um tweet que viralizou afirmou que a Microsoft considera que lan\u00e7ar jogos \u201cday one\u201d no lan\u00e7amento seria uma estrat\u00e9gia fracassada. Isso gerou forte repercuss\u00e3o, compartilhamentos em massa, mas realmente esta frase foi afirmada pela Microsoft? O espanhol eXtas1stv postou o seguinte","og:url":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/","article:published_time":"2026-07-14T23:50:47+00:00","article:modified_time":"2026-07-14T23:50:47+00:00","article:publisher":"https:\/\/www.facebook.com\/obewisenetwork","twitter:card":"summary_large_image","twitter:site":"@obewisenetwork","twitter:title":"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso? - Obewise","twitter:description":"O Xbox Game Pass se tornou alvo de uma nova pol\u00eamica nas redes sociais. Um tweet que viralizou afirmou que a Microsoft considera que lan\u00e7ar jogos \u201cday one\u201d no lan\u00e7amento seria uma estrat\u00e9gia fracassada. Isso gerou forte repercuss\u00e3o, compartilhamentos em massa, mas realmente esta frase foi afirmada pela Microsoft? O espanhol eXtas1stv postou o seguinte","twitter:creator":"@obewisenetwork"},"aioseo_meta_data":{"post_id":"23118","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-07-15 00:37:35","updated":"2026-07-15 00:37:35","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/obewise.com.br\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/obewise.com.br\/index.php\/category\/games\/\" title=\"Games\">Games<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/obewise.com.br\/index.php\/category\/games\/xbox\/\" title=\"Xbox\">Xbox<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAp\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso?\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/obewise.com.br"},{"label":"Games","link":"https:\/\/obewise.com.br\/index.php\/category\/games\/"},{"label":"Xbox","link":"https:\/\/obewise.com.br\/index.php\/category\/games\/xbox\/"},{"label":"Ap\u00f3s 9 anos, Microsoft acredita que lan\u00e7ar jogos direto no Xbox Game Pass \u00e9 um fracasso?","link":"https:\/\/obewise.com.br\/index.php\/2026\/07\/14\/apos-9-anos-microsoft-acredita-que-lancar-jogos-direto-no-xbox-game-pass-e-um-fracasso\/"}],"_links":{"self":[{"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23118"}],"version-history":[{"count":0,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/media\/13017"}],"wp:attachment":[{"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23118"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/coauthors?post=23118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}