{"id":23924,"date":"2026-09-01T21:04:41","date_gmt":"2026-09-01T21:04:41","guid":{"rendered":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/"},"modified":"2026-09-01T21:04:41","modified_gmt":"2026-09-01T21:04:41","slug":"razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone","status":"publish","type":"post","link":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/","title":{"rendered":"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone"},"content":{"rendered":"<p><\/p>\n<div>\n<p class=\"wp-block-paragraph\">A Razer entrou na comemora\u00e7\u00e3o dos 25 anos do Xbox com uma cole\u00e7\u00e3o especial de perif\u00e9ricos que aposta forte na nostalgia. A linha foi criada em parceria com a Microsoft e traz tr\u00eas produtos conhecidos da marca em uma vers\u00e3o in\u00e9dita com acabamento verde transl\u00facido inspirado no Xbox original de 2001.<\/p>\n<p class=\"wp-block-paragraph\">A cole\u00e7\u00e3o Razer Xbox 25 Anniversary \u00e9 formada pelo mouse Basilisk V3 Pro 35K, pelo teclado mec\u00e2nico BlackWidow V4 75% e pelos fones sem fio Hammerhead V3 X HyperSpeed para Xbox. Curiosamente, n\u00e3o h\u00e1 um controle entre os produtos da Razer, j\u00e1 que o joystick comemorativo faz parte de outra linha oficial da Microsoft.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1200\" src=\"https:\/\/nerdizmo.ig.com.br\/wp-content\/uploads\/2026\/08\/Razer-Xbox-25-anos-03.webp\" alt=\"\" class=\"wp-image-154222\" srcset=\"https:\/\/nerdizmo.ig.com.br\/wp-content\/uploads\/2026\/08\/Razer-Xbox-25-anos-03.webp 1200w, https:\/\/nerdizmo.ig.com.br\/wp-content\/uploads\/2026\/08\/Razer-Xbox-25-anos-03-768x768.webp 768w, https:\/\/nerdizmo.ig.com.br\/wp-content\/uploads\/2026\/08\/Razer-Xbox-25-anos-03-370x370.webp 370w, https:\/\/nerdizmo.ig.com.br\/wp-content\/uploads\/2026\/08\/Razer-Xbox-25-anos-03-150x150.webp 150w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"\/><\/figure>\n<p class=\"wp-block-paragraph\">O mouse \u00e9 o destaque para quem procura desempenho. Ele utiliza o sensor \u00f3ptico Focus Pro 35K de segunda gera\u00e7\u00e3o, possui 13 comandos personaliz\u00e1veis, conex\u00e3o sem fio HyperSpeed e ilumina\u00e7\u00e3o RGB. J\u00e1 o BlackWidow V4 75% \u00e9 um teclado compacto com switches mec\u00e2nicos Orange Tactile de terceira gera\u00e7\u00e3o e suporte para troca dos switches. Ele tamb\u00e9m traz uma tecla dedicada ao Xbox Game Bar.<\/p>\n<p class=\"wp-block-paragraph\">Nos fones, a proposta \u00e9 oferecer baixa lat\u00eancia para jogos. O Hammerhead V3 X HyperSpeed combina conex\u00e3o sem fio de 2,4 GHz com Bluetooth 5.3, tecnologia SmartSwitch, resist\u00eancia IPX4 e at\u00e9 35 horas de bateria. O modelo tamb\u00e9m oferece \u00e1udio surround em Xbox e PC.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"960\" src=\"https:\/\/nerdizmo.ig.com.br\/wp-content\/uploads\/2026\/08\/Razer-Xbox-25-anos-02.webp\" alt=\"\" class=\"wp-image-154223\" srcset=\"https:\/\/nerdizmo.ig.com.br\/wp-content\/uploads\/2026\/08\/Razer-Xbox-25-anos-02.webp 1200w, https:\/\/nerdizmo.ig.com.br\/wp-content\/uploads\/2026\/08\/Razer-Xbox-25-anos-02-768x614.webp 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"\/><\/figure>\n<p class=\"wp-block-paragraph\">Apesar das mudan\u00e7as visuais, o hardware \u00e9 essencialmente o mesmo encontrado nos modelos convencionais. O grande diferencial est\u00e1 no acabamento verde transl\u00facido, nos detalhes comemorativos e no apelo para colecionadores. Os tr\u00eas produtos ainda acompanham um m\u00eas de Xbox Game Pass Ultimate, sujeito \u00e0s condi\u00e7\u00f5es da promo\u00e7\u00e3o.<\/p>\n<p class=\"wp-block-paragraph\">Nos Estados Unidos, a edi\u00e7\u00e3o especial custa US$ 179,99 no caso do mouse, US$ 209,99 para o teclado e US$ 119,99 pelos fones. Ou seja, o pacote completo chega a US$ 509,97. No Brasil, ainda n\u00e3o h\u00e1 pre\u00e7o nem data de lan\u00e7amento confirmados para a cole\u00e7\u00e3o.<\/p>\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/nerdizmo.ig.com.br\/wp-content\/uploads\/2026\/08\/Razer-Xbox-25-anos-01.webp\" alt=\"\" class=\"wp-image-154224\" srcset=\"https:\/\/nerdizmo.ig.com.br\/wp-content\/uploads\/2026\/08\/Razer-Xbox-25-anos-01.webp 1200w, https:\/\/nerdizmo.ig.com.br\/wp-content\/uploads\/2026\/08\/Razer-Xbox-25-anos-01-768x432.webp 768w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\"\/><\/figure>\n<p class=\"wp-block-paragraph\">As pr\u00e9 vendas come\u00e7aram em agosto de 2026 nos Estados Unidos, com disponibilidade prevista para 20 de outubro. A cole\u00e7\u00e3o tamb\u00e9m foi apresentada durante a Gamescom 2026, onde a Razer mostrou os produtos em a\u00e7\u00f5es especiais relacionadas aos 25 anos do Xbox.<\/p>\n<p class=\"wp-block-paragraph\">Para quem cresceu com o Xbox original, o visual provavelmente ser\u00e1 a parte mais atraente. O verde transl\u00facido lembra diretamente o console lan\u00e7ado em 2001 e transforma perif\u00e9ricos comuns em pe\u00e7as que parecem ter sa\u00eddo de uma edi\u00e7\u00e3o comemorativa de luxo.<\/p>\n<p class=\"wp-block-paragraph\">Veja mais sobre games.<\/p>\n<p><!-- CONTENT END 1 --><\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Razer entrou na comemora\u00e7\u00e3o dos 25 anos do Xbox com uma cole\u00e7\u00e3o especial de perif\u00e9ricos que aposta forte na nostalgia. A linha foi criada em parceria com a Microsoft e traz tr\u00eas produtos conhecidos da marca em uma vers\u00e3o in\u00e9dita com acabamento verde transl\u00facido inspirado no Xbox original de 2001. A cole\u00e7\u00e3o Razer Xbox &hellip;<\/p>\n","protected":false},"author":1,"featured_media":23925,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_bbp_topic_count":0,"_bbp_reply_count":0,"_bbp_total_topic_count":0,"_bbp_total_reply_count":0,"_bbp_voice_count":0,"_bbp_anonymous_reply_count":0,"_bbp_topic_count_hidden":0,"_bbp_reply_count_hidden":0,"_bbp_forum_subforum_count":0,"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_shortscore_rating":"","_shortscore_game":"","_shortscore_summary":"","footnotes":""},"categories":[92],"tags":[887,2060,4216,10206,770,699,4520,5229,161],"coauthors":[393],"class_list":["post-23924","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geek","tag-anos","tag-colecao","tag-especial","tag-fone","tag-lanca","tag-mouse","tag-razer","tag-teclado","tag-xbox"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"A Razer entrou na comemora\u00e7\u00e3o dos 25 anos do Xbox com uma cole\u00e7\u00e3o especial de perif\u00e9ricos que aposta forte na nostalgia. A linha foi criada em parceria com a Microsoft e traz tr\u00eas produtos conhecidos da marca em uma vers\u00e3o in\u00e9dita com acabamento verde transl\u00facido inspirado no Xbox original de 2001. A cole\u00e7\u00e3o Razer Xbox\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Fagner Lopes\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Obewise - Entretenimento e Network\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone - Obewise\" \/>\n\t\t<meta property=\"og:description\" content=\"A Razer entrou na comemora\u00e7\u00e3o dos 25 anos do Xbox com uma cole\u00e7\u00e3o especial de perif\u00e9ricos que aposta forte na nostalgia. A linha foi criada em parceria com a Microsoft e traz tr\u00eas produtos conhecidos da marca em uma vers\u00e3o in\u00e9dita com acabamento verde transl\u00facido inspirado no Xbox original de 2001. A cole\u00e7\u00e3o Razer Xbox\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-09-01T21:04:41+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-09-01T21:04:41+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/obewisenetwork\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@obewisenetwork\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone - Obewise\" \/>\n\t\t<meta name=\"twitter:description\" content=\"A Razer entrou na comemora\u00e7\u00e3o dos 25 anos do Xbox com uma cole\u00e7\u00e3o especial de perif\u00e9ricos que aposta forte na nostalgia. A linha foi criada em parceria com a Microsoft e traz tr\u00eas produtos conhecidos da marca em uma vers\u00e3o in\u00e9dita com acabamento verde transl\u00facido inspirado no Xbox original de 2001. A cole\u00e7\u00e3o Razer Xbox\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@obewisenetwork\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#blogposting\",\"name\":\"Razer lan\\u00e7a cole\\u00e7\\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone - Obewise\",\"headline\":\"Razer lan\\u00e7a cole\\u00e7\\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone\",\"author\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/author\\\/fagnerlopes\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/Razer-Xbox-25-anos-04.webp\",\"width\":2000,\"height\":1125},\"datePublished\":\"2026-09-01T21:04:41+00:00\",\"dateModified\":\"2026-09-01T21:04:41+00:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#webpage\"},\"articleSection\":\"Geek, anos, cole\\u00e7\\u00e3o, especial, fone, lan\\u00e7a, mouse, Razer, teclado, Xbox, FagnerLopes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/obewise.com.br\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/geek\\\/#listItem\",\"name\":\"Geek\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/geek\\\/#listItem\",\"position\":2,\"name\":\"Geek\",\"item\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/geek\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#listItem\",\"name\":\"Razer lan\\u00e7a cole\\u00e7\\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#listItem\",\"position\":3,\"name\":\"Razer lan\\u00e7a cole\\u00e7\\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/category\\\/geek\\\/#listItem\",\"name\":\"Geek\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/#organization\",\"name\":\"Obewise Entertainment Network\",\"description\":\"Entretenimento e Network\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/\",\"telephone\":\"+5511963153854\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/abstract-logo-maker-for-corporations-1530.png\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#organizationLogo\",\"width\":4000,\"height\":4000},\"image\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/obewisenetwork\",\"https:\\\/\\\/twitter.com\\\/obewisenetwork\",\"https:\\\/\\\/www.instagram.com\\\/obewise.network\\\/\",\"https:\\\/\\\/soundcloud.com\\\/obewiseradio\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/author\\\/fagnerlopes\\\/#author\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/author\\\/fagnerlopes\\\/\",\"name\":\"Fagner Lopes\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#authorImage\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/wp-content\\\/uploads\\\/avatars\\\/1\\\/1668544069-bpfull.jpg\",\"width\":96,\"height\":96,\"caption\":\"Fagner Lopes\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#webpage\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/\",\"name\":\"Razer lan\\u00e7a cole\\u00e7\\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone - Obewise\",\"description\":\"A Razer entrou na comemora\\u00e7\\u00e3o dos 25 anos do Xbox com uma cole\\u00e7\\u00e3o especial de perif\\u00e9ricos que aposta forte na nostalgia. A linha foi criada em parceria com a Microsoft e traz tr\\u00eas produtos conhecidos da marca em uma vers\\u00e3o in\\u00e9dita com acabamento verde transl\\u00facido inspirado no Xbox original de 2001. A cole\\u00e7\\u00e3o Razer Xbox\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/author\\\/fagnerlopes\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/author\\\/fagnerlopes\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/wp-content\\\/uploads\\\/2026\\\/09\\\/Razer-Xbox-25-anos-04.webp\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#mainImage\",\"width\":2000,\"height\":1125},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/index.php\\\/2026\\\/09\\\/01\\\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\\\/#mainImage\"},\"datePublished\":\"2026-09-01T21:04:41+00:00\",\"dateModified\":\"2026-09-01T21:04:41+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/obewise.com.br\\\/#website\",\"url\":\"https:\\\/\\\/obewise.com.br\\\/\",\"name\":\"Obewise\",\"description\":\"Entretenimento e Network\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/obewise.com.br\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone - Obewise","description":"A Razer entrou na comemora\u00e7\u00e3o dos 25 anos do Xbox com uma cole\u00e7\u00e3o especial de perif\u00e9ricos que aposta forte na nostalgia. A linha foi criada em parceria com a Microsoft e traz tr\u00eas produtos conhecidos da marca em uma vers\u00e3o in\u00e9dita com acabamento verde transl\u00facido inspirado no Xbox original de 2001. A cole\u00e7\u00e3o Razer Xbox","canonical_url":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#blogposting","name":"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone - Obewise","headline":"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone","author":{"@id":"https:\/\/obewise.com.br\/index.php\/author\/fagnerlopes\/#author"},"publisher":{"@id":"https:\/\/obewise.com.br\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/obewise.com.br\/wp-content\/uploads\/2026\/09\/Razer-Xbox-25-anos-04.webp","width":2000,"height":1125},"datePublished":"2026-09-01T21:04:41+00:00","dateModified":"2026-09-01T21:04:41+00:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#webpage"},"isPartOf":{"@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#webpage"},"articleSection":"Geek, anos, cole\u00e7\u00e3o, especial, fone, lan\u00e7a, mouse, Razer, teclado, Xbox, FagnerLopes"},{"@type":"BreadcrumbList","@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/obewise.com.br#listItem","position":1,"name":"Home","item":"https:\/\/obewise.com.br","nextItem":{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/category\/geek\/#listItem","name":"Geek"}},{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/category\/geek\/#listItem","position":2,"name":"Geek","item":"https:\/\/obewise.com.br\/index.php\/category\/geek\/","nextItem":{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#listItem","name":"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone"},"previousItem":{"@type":"ListItem","@id":"https:\/\/obewise.com.br#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#listItem","position":3,"name":"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone","previousItem":{"@type":"ListItem","@id":"https:\/\/obewise.com.br\/index.php\/category\/geek\/#listItem","name":"Geek"}}]},{"@type":"Organization","@id":"https:\/\/obewise.com.br\/#organization","name":"Obewise Entertainment Network","description":"Entretenimento e Network","url":"https:\/\/obewise.com.br\/","telephone":"+5511963153854","logo":{"@type":"ImageObject","url":"https:\/\/obewise.com.br\/wp-content\/uploads\/2022\/12\/abstract-logo-maker-for-corporations-1530.png","@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#organizationLogo","width":4000,"height":4000},"image":{"@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/obewisenetwork","https:\/\/twitter.com\/obewisenetwork","https:\/\/www.instagram.com\/obewise.network\/","https:\/\/soundcloud.com\/obewiseradio"]},{"@type":"Person","@id":"https:\/\/obewise.com.br\/index.php\/author\/fagnerlopes\/#author","url":"https:\/\/obewise.com.br\/index.php\/author\/fagnerlopes\/","name":"Fagner Lopes","image":{"@type":"ImageObject","@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#authorImage","url":"https:\/\/obewise.com.br\/wp-content\/uploads\/avatars\/1\/1668544069-bpfull.jpg","width":96,"height":96,"caption":"Fagner Lopes"}},{"@type":"WebPage","@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#webpage","url":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/","name":"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone - Obewise","description":"A Razer entrou na comemora\u00e7\u00e3o dos 25 anos do Xbox com uma cole\u00e7\u00e3o especial de perif\u00e9ricos que aposta forte na nostalgia. A linha foi criada em parceria com a Microsoft e traz tr\u00eas produtos conhecidos da marca em uma vers\u00e3o in\u00e9dita com acabamento verde transl\u00facido inspirado no Xbox original de 2001. A cole\u00e7\u00e3o Razer Xbox","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/obewise.com.br\/#website"},"breadcrumb":{"@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#breadcrumblist"},"author":{"@id":"https:\/\/obewise.com.br\/index.php\/author\/fagnerlopes\/#author"},"creator":{"@id":"https:\/\/obewise.com.br\/index.php\/author\/fagnerlopes\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/obewise.com.br\/wp-content\/uploads\/2026\/09\/Razer-Xbox-25-anos-04.webp","@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#mainImage","width":2000,"height":1125},"primaryImageOfPage":{"@id":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/#mainImage"},"datePublished":"2026-09-01T21:04:41+00:00","dateModified":"2026-09-01T21:04:41+00:00"},{"@type":"WebSite","@id":"https:\/\/obewise.com.br\/#website","url":"https:\/\/obewise.com.br\/","name":"Obewise","description":"Entretenimento e Network","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/obewise.com.br\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"Obewise - Entretenimento e Network","og:type":"article","og:title":"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone - Obewise","og:description":"A Razer entrou na comemora\u00e7\u00e3o dos 25 anos do Xbox com uma cole\u00e7\u00e3o especial de perif\u00e9ricos que aposta forte na nostalgia. A linha foi criada em parceria com a Microsoft e traz tr\u00eas produtos conhecidos da marca em uma vers\u00e3o in\u00e9dita com acabamento verde transl\u00facido inspirado no Xbox original de 2001. A cole\u00e7\u00e3o Razer Xbox","og:url":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/","article:published_time":"2026-09-01T21:04:41+00:00","article:modified_time":"2026-09-01T21:04:41+00:00","article:publisher":"https:\/\/www.facebook.com\/obewisenetwork","twitter:card":"summary_large_image","twitter:site":"@obewisenetwork","twitter:title":"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone - Obewise","twitter:description":"A Razer entrou na comemora\u00e7\u00e3o dos 25 anos do Xbox com uma cole\u00e7\u00e3o especial de perif\u00e9ricos que aposta forte na nostalgia. A linha foi criada em parceria com a Microsoft e traz tr\u00eas produtos conhecidos da marca em uma vers\u00e3o in\u00e9dita com acabamento verde transl\u00facido inspirado no Xbox original de 2001. A cole\u00e7\u00e3o Razer Xbox","twitter:creator":"@obewisenetwork"},"aioseo_meta_data":{"post_id":"23924","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2026-09-01 21:51:53","updated":"2026-09-01 21:51:53","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/obewise.com.br\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/obewise.com.br\/index.php\/category\/geek\/\" title=\"Geek\">Geek<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tRazer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/obewise.com.br"},{"label":"Geek","link":"https:\/\/obewise.com.br\/index.php\/category\/geek\/"},{"label":"Razer lan\u00e7a cole\u00e7\u00e3o especial de 25 anos do Xbox com mouse, teclado e fone","link":"https:\/\/obewise.com.br\/index.php\/2026\/09\/01\/razer-lanca-colecao-especial-de-25-anos-do-xbox-com-mouse-teclado-e-fone\/"}],"_links":{"self":[{"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23924","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=23924"}],"version-history":[{"count":0,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/posts\/23924\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/media\/23925"}],"wp:attachment":[{"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=23924"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=23924"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=23924"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/obewise.com.br\/index.php\/wp-json\/wp\/v2\/coauthors?post=23924"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}